{"id":1154,"date":"2012-12-21T19:42:19","date_gmt":"2012-12-21T19:42:19","guid":{"rendered":"http:\/\/rediles.com\/atletismo\/?p=1154"},"modified":"2015-03-21T22:51:57","modified_gmt":"2015-03-21T22:51:57","slug":"series-en-cinta","status":"publish","type":"post","link":"http:\/\/rediles.com\/atletismo\/2012\/12\/21\/series-en-cinta\/","title":{"rendered":"Series en cinta."},"content":{"rendered":"<p>Hoy vamos a centrarnos en las inquietudes invernales del amigo David.<\/p>\n<p><em>Buenas tardes Cesar, quisiera <\/em><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/lh4.googleusercontent.com\/-T8s-jjTla3I\/UNWA-5v_z3I\/AAAAAAAABHM\/B4K6van78mQ\/s402\/800px-Fitness_Center.JPG\" alt=\"\" width=\"298\" height=\"180\" \/><\/em><em>saber tu <\/em><em>opinion sobre hacer series en la cinta. Con el mal tiempo a veces se hace duro salir (de noche y ademas solo), asi que, \u00bfpuede ser una alternativa? Ademas que para los que no tenemos GPS nos es de ayuda, pero lo que tengo dudas es de su efectividad, \u00bfnos aportas algo de luz? GRACIAS<\/em><\/p>\n<p>Hola David, veo que a ti tambi\u00e9n te arruga un poquillo el fr\u00edo. Pero respondiendo a tu pregunta, \u00a1por supuesto!, las series en cinta no solo son una alternativa, sino que adem\u00e1s su gran efectividad est\u00e1 fuera de toda duda.<\/p>\n<p>Quisiera remarcar en primer lugar, la gran importancia de hacer las series con al menos uno o dos puntos de inclinaci\u00f3n en la cinta. Tambi\u00e9n aconsejo realizar la sesi\u00f3n viendo alg\u00fan programa de nuestro agrado en la tele o con m\u00fasica, pues la cinta puede resultar bastante tediosa. Precisamente las series o aceleraciones cortas pueden ser un buen elemento, no solo para ganar velocidad, tambi\u00e9n hacen la sesi\u00f3n menos aburrida.<\/p>\n<p>Hay quien desprecia las sesiones en este aparato, aduciendo que la cinta empuja los pies y por lo tanto las piernas sufren menos, puede que sea cierto, pero yo he probado estos aparatos a 20km\/h con alg\u00fan punto de desnivel, y os aseguro que solo un gran profesional es capaz de aguantar 10 minutos solamente. Lo problem\u00e1tico en este aparato no es la falta de dureza o resultados, sino todo lo contrario, hay que tener mucho cuidado en no pasarse de la raya corriendo demasiado tiempo, demasiado r\u00e1pido, o con demasiado desnivel, este \u00faltimo aspecto puede causarnos molestias en las rodillas.<\/p>\n<p>Pero tampoco hay que alarmarse demasiado, normalmente la propia dureza del ejercicio nos pone en nuestro sitio. El ejercicio en cinta es muy completo, y muchos atletas profesionales, sobre todo n\u00f3rdicos, alcanzan fabulosos estados de forma corriendo solo y exclusivamente en estos aparatos.<\/p>\n<p>Por lo tanto animo sin ninguna duda, a utilizar estos aparatos a David y a todos los que tengan la fortuna de tenerlos a su disposici\u00f3n. En el art\u00edculo <a href=\"http:\/\/rediles.com\/atletismo\/2010\/10\/10\/correr-en-cinta\/\" target=\"_blank\">\u00abCorrer en cinta\u00bb<\/a> tambi\u00e9n doy algo de informaci\u00f3n al respecto. Un saludo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy vamos a centrarnos en las inquietudes invernales del amigo David. Buenas tardes Cesar, quisiera saber tu opinion sobre hacer series en la cinta. Con el mal tiempo a veces se hace duro salir (de noche y ademas solo), asi &hellip; <a href=\"http:\/\/rediles.com\/atletismo\/2012\/12\/21\/series-en-cinta\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-1154","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/posts\/1154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/comments?post=1154"}],"version-history":[{"count":2,"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/posts\/1154\/revisions"}],"predecessor-version":[{"id":1316,"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/posts\/1154\/revisions\/1316"}],"wp:attachment":[{"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/media?parent=1154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/categories?post=1154"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/rediles.com\/atletismo\/wp-json\/wp\/v2\/tags?post=1154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}